{"id":14043,"date":"2020-10-13T14:48:38","date_gmt":"2020-10-13T19:48:38","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=14043"},"modified":"2024-04-21T21:40:53","modified_gmt":"2024-04-22T02:40:53","slug":"barrera-peatonal-con-deteccion-facial-y-temperatura-sbtl8033-td","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/barrera-peatonal-con-deteccion-facial-y-temperatura-sbtl8033-td\/","title":{"rendered":"BARRERA PEATONAL CON DETECCION FACIAL Y TEMPERATURA &#8211; SBTL8033 [TD]"},"content":{"rendered":"<p>BARRERA PEATONAL CON DETECCION FACIAL Y TEMPERATURA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BARRERA PEATONAL CON DETECCION FACIAL Y TEMPERATURA<\/p>\n<p>Voltaje de Operaci\u00f3n AC 100 ~ 120V\/200 ~ 240V, 50\/60Hz<br \/>\nTemperatura de Operaci\u00f3n -28\u00b0C~ 60\u00b0C<br \/>\nHumedad Relativa 20%-95% (Sin condensaci\u00f3n)<br \/>\nEntorno de operaci\u00f3n Interior<br \/>\nVelodidad de paso M\u00e1ximo 40\/ minuto<br \/>\nAncho de carril (mm) 660 m<br \/>\nPeso Neto (kg) 130 kg<br \/>\nMaterial del Gabinete Acero inoxidable.<br \/>\nMaterial de las Paredes de la Barrera Acero inoxidable.<br \/>\nMaterial de la Puerta Acr\u00edlico<br \/>\nTipo de Apertura Abatible<\/p>\n<p>PROFACE X (TD) Cap. 30000 rostros 50000<br \/>\nDistancia de reconocimiento 3 m.<br \/>\nDesviacion de Temperatura +\/- 0.5 grados<br \/>\nDistancia de detecci\u00f3n de temperatura corporal 25cm \u2013 50cm<br \/>\nVelocidad de lectura de temperatura corporal &gt;0.3s<br \/>\nTolerancia de postura +\/-30 grados- Software Web ZKBIOSECURITY V5000 2.0<\/p>\n","protected":false},"featured_media":14044,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[344],"product_tag":[58],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/14043"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=14043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/14044"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=14043"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=14043"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=14043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}