{"id":14467,"date":"2020-10-23T15:34:40","date_gmt":"2020-10-23T20:34:40","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=14467"},"modified":"2024-04-21T21:45:02","modified_gmt":"2024-04-22T02:45:02","slug":"sirena-12vdc-30w-para-exteriores-sir-115","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/sirena-12vdc-30w-para-exteriores-sir-115\/","title":{"rendered":"Sirena 12VDC 30W para Exteriores &#8211; SIR-115"},"content":{"rendered":"<p>Sirena 12VDC 30W para Exteriores<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sirena 12VDC 30W para Exteriores, para uso de Paneles de alarmas y cerco electrico con 2 sonidos- POTENCIA 30W,- 115 +- 5 dB<\/p>\n<p>Para uso de Paneles de alarmas y cerco electrico con 2 sonidos<br \/>\n&#8211; POTENCIA 30W,- 115 +- 5 dB<\/p>\n","protected":false},"featured_media":14468,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[371],"product_tag":[304],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/14467"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=14467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/14468"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=14467"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=14467"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=14467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}