{"id":14506,"date":"2020-10-24T08:53:13","date_gmt":"2020-10-24T13:53:13","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=14506"},"modified":"2025-03-27T16:53:09","modified_gmt":"2025-03-27T21:53:09","slug":"wifi-socket-orv-s25us","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/wifi-socket-orv-s25us\/","title":{"rendered":"ORV-S25US | WiFi SOCKET"},"content":{"rendered":"<p>WiFi SOCKET<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WiFi SOCKET<\/p>\n<p>\u2022 Controle de manera remota sus electrodom\u00e9sticos a trav\u00e9s de la aplicaci\u00f3n de tel\u00e9fono.<br \/>\n\u2022 Compruebe el estado de los aparatos en cualquier momento y ahorre energ\u00eda.<br \/>\n\u2022 Configurar el temporizador para encender \/ apagar el z\u00f3calo inteligente.<br \/>\n\u2022 Caracter\u00edsticas T\u00e9cnicas :<br \/>\n&#8211; Voltaje de Entrada: 220 VAC, 60 Hz, 10 A.<br \/>\n&#8211; Voltaje de Entrada: 220 VAC, 60 Hz, 10 A.<\/p>\n<p>* Se conecta directamente a la Red El\u00e9ctrica.<\/p>\n","protected":false},"featured_media":14507,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[297],"product_tag":[378],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/14506"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=14506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/14507"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=14506"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=14506"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=14506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}