{"id":14716,"date":"2020-11-05T12:45:42","date_gmt":"2020-11-05T17:45:42","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=14716"},"modified":"2024-04-21T21:48:02","modified_gmt":"2024-04-22T02:48:02","slug":"cable-conversor-usb-para-programacion-de-centrales-de-alarmas-jfl-jfl-2-2-2-24","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/cable-conversor-usb-para-programacion-de-centrales-de-alarmas-jfl-jfl-2-2-2-24\/","title":{"rendered":"Cable conversor USB para programaci\u00f3n de centrales de alarmas JFL &#8211; JFL-2.2.2.24"},"content":{"rendered":"<p>Cable conversor USB para programaci\u00f3n de centrales de alarmas JFL<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cable conversor USB para programaci\u00f3n de centrales de alarmas JFL.<\/p>\n<p>&#8211; USB 2.0.<br \/>\n&#8211; Compatible con sistemas operativos Windows, Linux e iOS.<\/p>\n","protected":false},"featured_media":14717,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[297],"product_tag":[375],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/14716"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=14716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/14717"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=14716"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=14716"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=14716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}