{"id":16983,"date":"2022-02-11T11:35:15","date_gmt":"2022-02-11T16:35:15","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=16983"},"modified":"2024-04-21T21:57:31","modified_gmt":"2024-04-22T02:57:31","slug":"vto6521h-d-frente-de-calle-ip-para-edificios","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/vto6521h-d-frente-de-calle-ip-para-edificios\/","title":{"rendered":"VTO6521H-D &#8211; FRENTE DE CALLE IP PARA EDIFICIOS"},"content":{"rendered":"<table id=\"table001\" class=\"NEW-TABLE TableOverride-1 tab-drag\">\n<tbody>\n<tr>\n<td colspan=\"60\">Sistema<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Procesador principal<\/td>\n<td colspan=\"42\">Procesador integrado<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Sistema operativo<\/td>\n<td colspan=\"42\">Sistema operativo Linux integrado<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tipo de bot\u00f3n<\/td>\n<td colspan=\"42\">bot\u00f3n t\u00e1ctil<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Protocolo de red<\/td>\n<td colspan=\"42\">SORBO;\u00a0P2P;\u00a0IPv4;\u00a0FTP;\u00a0UPnP;\u00a0DNS;\u00a0DDNS;\u00a0RTSP;\u00a0RTP;\u00a0TCP;\u00a0UDP<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">ROM<\/td>\n<td colspan=\"42\">4 GB<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">RAM<\/td>\n<td colspan=\"42\">1GB<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">B\u00e1sico<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Pantalla de visualizaci\u00f3n<\/td>\n<td colspan=\"42\">Pantalla IPS de 4,3 pulgadas<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Resoluci\u00f3n<\/td>\n<td colspan=\"42\">800\u00d7480<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">C\u00e1mara<\/td>\n<td colspan=\"42\">CMOS de 1\/2,7&#8243; y 2 MP de alta definici\u00f3n, baja iluminaci\u00f3n, iluminador blanco e iluminador IR<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Campo de visi\u00f3n<\/td>\n<td colspan=\"42\">horizontales: 113,79\u00b0;\u00a0verticales: 61,5\u00b0;<\/p>\n<p>diagonal: 134,45\u00b0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Longitud focal<\/td>\n<td colspan=\"42\">2,8mm<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Abertura<\/td>\n<td colspan=\"42\">F2.0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">WDR<\/td>\n<td colspan=\"42\">120dB<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Reducci\u00f3n de ruido<\/td>\n<td colspan=\"42\">reducci\u00f3n de ruido 3D<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Compresi\u00f3n de video<\/td>\n<td colspan=\"42\">H.264<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Resoluci\u00f3n de video<\/td>\n<td colspan=\"42\">Transmisi\u00f3n principal: 720p, transmisi\u00f3n secundaria: 1080P<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Cuadros por segundo<\/td>\n<td colspan=\"42\">Transmisi\u00f3n principal (720P@25fps), transmisi\u00f3n secundaria (1080P@25fps) Transmisi\u00f3n<br \/>\nprincipal (720P@30fps), transmisi\u00f3n secundaria (1080P@30fps)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Bitrate de v\u00eddeo<\/td>\n<td colspan=\"42\">256 Kbps\u20132048 Kbps<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Compensaci\u00f3n de luz<\/td>\n<td colspan=\"42\">Luz blanca autom\u00e1tica<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Compresi\u00f3n de audio<\/td>\n<td colspan=\"42\">G.711u<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Entrada de audio<\/td>\n<td colspan=\"42\">1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Salida de audio<\/td>\n<td colspan=\"42\">Altavoz incorporado<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Modo audio<\/td>\n<td colspan=\"42\">Comunicaci\u00f3n d\u00faplex completo<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Mejora de audio<\/td>\n<td colspan=\"42\">Supresi\u00f3n y cancelaci\u00f3n de eco\/reducci\u00f3n de ruido digital<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tasa de bits de audio<\/td>\n<td colspan=\"42\">16 KHz, 16 bits<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Modo de comunicaci\u00f3n<\/td>\n<td colspan=\"42\">digital completo<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Modo de desbloqueo<\/td>\n<td colspan=\"42\">Desbloqueo de tarjeta\/remoto\/contrase\u00f1a<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tipo de tarjeta<\/td>\n<td colspan=\"42\">tarjeta de identificaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Detecci\u00f3n de movimiento<\/td>\n<td colspan=\"42\">Detecci\u00f3n de movimiento de v\u00eddeo<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Instant\u00e1nea autom\u00e1tica<\/td>\n<td colspan=\"42\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Deja videos o mensajes de texto<\/td>\n<td colspan=\"42\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Configuraci\u00f3n Web<\/td>\n<td colspan=\"42\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Distancia de lectura de tarjeta<\/td>\n<td colspan=\"42\">1cm\u20135cm<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Emitir tarjeta localmente<\/td>\n<td colspan=\"42\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Material de la carcasa<\/td>\n<td colspan=\"42\">PC+ABS<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Capacidad<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tarjeta<\/td>\n<td colspan=\"42\">10, 000<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Puerto<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">RS-485<\/td>\n<td colspan=\"42\">1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Wiegand<\/td>\n<td colspan=\"42\">1 puerto de entrada, 1 puerto de salida<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">cerradura electrica<\/td>\n<td colspan=\"42\">1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Entrada de alarma<\/td>\n<td colspan=\"42\">2<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Salida de alarma<\/td>\n<td colspan=\"42\">2<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Salida de potencia<\/td>\n<td colspan=\"42\">1 12V\/100mA<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Bot\u00f3n de salida<\/td>\n<td colspan=\"42\">1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Detecci\u00f3n del estado de la puerta<\/td>\n<td colspan=\"42\">1<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Control de bloqueo<\/td>\n<td colspan=\"42\">1, normalmente abierto por defecto<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Red<\/td>\n<td colspan=\"42\">1 RJ-45 10Mbps\/100Mbps autoadaptable<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Alarma<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Manosear<\/td>\n<td colspan=\"42\">s\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">General<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Desbloquear el modo de contrase\u00f1a<\/td>\n<td colspan=\"42\">Contrase\u00f1a de usuario\/contrase\u00f1a p\u00fablica\/contrase\u00f1a de coacci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Color<\/td>\n<td colspan=\"42\">Plata<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Modo de fuente de alimentaci\u00f3n<\/td>\n<td colspan=\"42\">CC 12V2A<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Adaptador de corriente<\/td>\n<td colspan=\"42\">Opcional<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Instalaci\u00f3n<\/td>\n<td colspan=\"42\">Montaje en superficie y montaje empotrado<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Certificaci\u00f3n<\/td>\n<td colspan=\"42\">CE\/FCC<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Accesorio<\/td>\n<td colspan=\"42\">Opcional<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Dimensiones del producto<\/td>\n<td colspan=\"42\">388,5 mm \u00d7 145,5 mm \u00d7 43,5 mm (15,30&#8243; \u00d7 5,73&#8243; \u00d7 1,71&#8243;)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Grado de protecci\u00f3n<\/td>\n<td colspan=\"42\">IP65 (se necesita sellador de silicona, consulte la gu\u00eda de inicio r\u00e1pido)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Temperatura de funcionamiento<\/td>\n<td colspan=\"42\">-30 \u00b0C a +60 \u00b0C (-22 \u00b0F a +140 \u00b0F)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Humedad de funcionamiento<\/td>\n<td colspan=\"42\">10 % de HR\u201390 % de HR (sin condensaci\u00f3n)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Altitud de funcionamiento<\/td>\n<td colspan=\"42\">86kPa\u2013106kPa<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">El consumo de energ\u00eda<\/td>\n<td colspan=\"42\">\u22645W (en espera), \u226418W (en funcionamiento)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Peso neto<\/td>\n<td colspan=\"42\">1,0 kg (2,20 libras)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Peso bruto<\/td>\n<td colspan=\"42\">1,29 kg (2,84 libras)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>FRENTE DE CALLE IP PARA EDIFICIOS<br \/>\n+ C\u00e1mara 2MP CMOS; true WDR<br \/>\n+ Pantalla 4.3 inch IPS display; screen resolution 800\u00d7480<br \/>\n+ Support 20, 000 users and 10, 000 cards<br \/>\n+ Support SIP server, and can manage 200 indoor monitors at most<br \/>\n+ Montaje en superficie y empotrado,<br \/>\n+ Alimentaci\u00f3n DC 12V2A<\/p>\n","protected":false},"featured_media":16984,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[133],"product_tag":[51,539],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/16983"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=16983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/16984"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=16983"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=16983"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=16983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}