{"id":17678,"date":"2022-03-10T08:47:27","date_gmt":"2022-03-10T13:47:27","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=17678"},"modified":"2025-03-27T16:39:55","modified_gmt":"2025-03-27T21:39:55","slug":"ucm6308-centrales-ip-pbx","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/ucm6308-centrales-ip-pbx\/","title":{"rendered":"CENTRALES IP PBX | UCM6308"},"content":{"rendered":"<p>Soporta hasta 3000 registros, 450 llamadas en simultaneo, 8 puerto FXO, 8 Puertos FXS, Video 1080p, video conferencia de 300 participante<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UCM-6308<\/p>\n<ul>\n<li>Soporta hasta 3000 registros de terminal SIP, hasta 450 llamadas simultaneas.<\/li>\n<li>8 Puertos FXO integrados para troncales PSTN. Video 1080p full HD video conferencia 80 participantes y audio conferencia 300<\/li>\n<li>8 puertos FXS anal\u00f3gicos de telefono con capacidad de respaldo en caso de interrupcion de la energia el\u00e9ctrica y hasta 50 cuentas de troncal SIP.<\/li>\n<li>3 Puertos de red Gigabit con PoE integrado, USB, tarjeta SD.<\/li>\n<li>UCM6308 incluye un router NAT integrado.<\/li>\n<li>Proteccion de seguridad global usando SRTP, TLS y HTTPS.<\/li>\n<\/ul>\n","protected":false},"featured_media":17680,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1929],"product_tag":[130,666],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/17678"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=17678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/17680"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=17678"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=17678"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=17678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}