{"id":18459,"date":"2022-05-24T12:59:55","date_gmt":"2022-05-24T17:59:55","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=18459"},"modified":"2025-03-27T16:49:00","modified_gmt":"2025-03-27T21:49:00","slug":"dgs-1510-52x-switch-gigabit-administrable","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/dgs-1510-52x-switch-gigabit-administrable\/","title":{"rendered":"DGS-1510-52X | SWITCH ADMINISTRABLE CAPA 2 Y 3"},"content":{"rendered":"<h4 class=\"vc_custom_heading\">Switches L3 SmartPro Gigabit Stackeable con 10G Uplinks<\/h4>\n<p class=\"vc_custom_heading\">Esta serie es la siguiente generaci\u00f3n de Switches Administrables Smart con capacidad de puertos 10G. Existen modelos de 16, 24 o 48 puertos 10\/100\/1000 Mbps m\u00e1s puertos en fibra Gigabit SFP y\/o 10G SFP+, as\u00ed como algunos modelos con soporte de PoE. Esta serie es ideal para implementaciones en SME\/SMB con la necesidad de uplinks de 10G.<\/p>\n","protected":false},"excerpt":{"rendered":"<h4 class=\"vc_custom_heading\">CARACTER\u00cdTICAS DESTACADAS<\/h4>\n<ul>\n<li class=\"vc_custom_heading\"><strong>CLI est\u00e1ndar:<\/strong> Compatible con CLI, una completa interfaz de l\u00ednea de comandos est\u00e1ndar para la administraci\u00f3n avanzada de la red<\/li>\n<li class=\"vc_custom_heading\"><strong>Apilamiento f\u00edsico:\u00a0 <\/strong>Se apilan f\u00edsicamente hasta 6 unidades para un total de 288 puertos.<\/li>\n<li class=\"vc_custom_heading\"><strong>Puertos SFP+ 10 G: <\/strong>Apile o con\u00e9ctese a otras \u00e1reas de su red a velocidades de 10 Gigabits con puertos SFP+.<\/li>\n<li class=\"vc_custom_heading\"><strong>M\u00faltiples im\u00e1genes y configuraci\u00f3n del firmware: <\/strong>Actualizaciones de firmware sin riesgos y pruebas de configuraci\u00f3n.<\/li>\n<li class=\"vc_custom_heading\"><strong>Static Routing:<\/strong> Enrute el tr\u00e1fico de Layer 3 entre switches, incluso si est\u00e1n segmentados en VLAN.<\/li>\n<\/ul>\n","protected":false},"featured_media":18460,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1839],"product_tag":[784,746],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/18459"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=18459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/18460"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=18459"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=18459"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=18459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}