{"id":18497,"date":"2022-06-02T12:30:52","date_gmt":"2022-06-02T17:30:52","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=18497"},"modified":"2025-03-27T16:50:08","modified_gmt":"2025-03-27T21:50:08","slug":"sf-alambrico-sensor-de-flexion-para-cerco-electrico","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/sf-alambrico-sensor-de-flexion-para-cerco-electrico\/","title":{"rendered":"SF-ALAMBRICO | SENSOR DE FLEXION PARA CERCO ELECTRICO"},"content":{"rendered":"<p><strong>Caracter\u00edsticas clave:<\/strong><\/p>\n<ul>\n<li><strong>Tecnolog\u00eda de sensor flexible:\u00a0<\/strong>emplea un sensor flexible que detecta cambios en la tensi\u00f3n o el \u00e1ngulo de la l\u00ednea de la cerca, identificando eficazmente manipulaciones o intentos de eludir la cerca.<\/li>\n<li><strong>Alta sensibilidad:\u00a0<\/strong>Proporciona alta sensibilidad incluso ante flexiones o movimientos menores de la cerca, lo que garantiza la detecci\u00f3n oportuna de intrusiones.<\/li>\n<li><strong>Dise\u00f1o resistente a la intemperie:\u00a0<\/strong>encerrado en una carcasa resistente a la intemperie, lo que lo hace adecuado para uso en exteriores en diversas condiciones clim\u00e1ticas.<\/li>\n<li><strong>F\u00e1cil instalaci\u00f3n:\u00a0<\/strong>se puede fijar f\u00e1cilmente a la l\u00ednea de la cerca mediante bridas o soportes de montaje.<\/li>\n<li><strong>Salida normalmente cerrada (NC):\u00a0<\/strong>proporciona una salida normalmente cerrada (NC), que env\u00eda una se\u00f1al al sistema de alarma o al panel de monitoreo cuando se manipula la cerca.<\/li>\n<li><strong>Compatible con varios sistemas:\u00a0<\/strong>funciona con varios sistemas de alarma, paneles de monitoreo y controladores de cercas el\u00e9ctricas que admiten conexiones cableadas.<\/li>\n<\/ul>\n<p><strong>Beneficios:<\/strong><\/p>\n<ul>\n<li><strong>Seguridad de cerca mejorada:\u00a0<\/strong>detecta manipulaciones e intentos de acceso no autorizados, salvaguardando su propiedad y disuadiendo a los intrusos.<\/li>\n<li><strong>Detecci\u00f3n temprana de intrusiones:\u00a0<\/strong>la alta sensibilidad garantiza la detecci\u00f3n oportuna de violaciones de la cerca, lo que permite una respuesta r\u00e1pida y la prevenci\u00f3n de posibles da\u00f1os o robos.<\/li>\n<li><strong>Construcci\u00f3n duradera:\u00a0<\/strong>el dise\u00f1o resistente a la intemperie soporta duras condiciones exteriores, lo que garantiza un rendimiento confiable en diversos climas.<\/li>\n<li><strong>Instalaci\u00f3n sencilla:\u00a0<\/strong>La f\u00e1cil fijaci\u00f3n a la l\u00ednea de la cerca mediante bridas o soportes de montaje minimiza el tiempo y el esfuerzo de instalaci\u00f3n.<\/li>\n<li><strong>Integraci\u00f3n flexible:\u00a0<\/strong>Compatible con varios sistemas de seguridad, lo que lo convierte en una adici\u00f3n adaptable a su configuraci\u00f3n de seguridad existente.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>SENSOR DE FLEXION<\/p>\n<ul>\n<li>Cuenta con protecci\u00f3n UV<\/li>\n<li>A\u00edsla hasta 15000V<\/li>\n<li>Soporta hasta 50Kg de tensi\u00f3n<\/li>\n<li>Rampa auto ajustable para el cierre del contacto<\/li>\n<li>Distancia de transmisi\u00f3n sin obst\u00e1culo: 80m<\/li>\n<\/ul>\n","protected":false},"featured_media":18498,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[371],"product_tag":[122,376],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/18497"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=18497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/18498"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=18497"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=18497"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=18497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}