{"id":19471,"date":"2022-09-13T18:05:35","date_gmt":"2022-09-13T23:05:35","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=19471"},"modified":"2024-04-21T22:12:08","modified_gmt":"2024-04-22T03:12:08","slug":"kit-vista128fbpt-paneles-convencionales-y-direccionables","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/kit-vista128fbpt-paneles-convencionales-y-direccionables\/","title":{"rendered":"KIT VISTA128FBPT | PANEL HIBRIDO DE INCENDIO E INTRUSION HASTA 128 ZONAS CABLEADAS O INALAMBRICAS"},"content":{"rendered":"<p><strong>PANEL HIBRIDO DE INCENDIO E INTRUSION HASTA 128 ZONAS CABLEADAS O INALAMBRICAS<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PANEL HIBRIDO DE INCENDIO E INTRUSION HASTA 128 ZONAS CABLEADAS O INALAMBRICAS<\/p>\n<ul>\n<li>DIRECCIONABLE (V-PLEX)- Soporta Detectores Convencionales de 02 y 04 hilos.<\/li>\n<li>Controla hasta 08 \u00e1reas independientes (08 Particiones)<\/li>\n<li>8 zonas cableadas en paca, expandible hasta 120 zonas VPLEX.<\/li>\n<li>Soporta 128 zonas inalambricas, agregando e receptor de honeywell (VI5881ENH).<\/li>\n<li>02 NACS en placa en total 2.3A a 12V.<\/li>\n<li>Almacena hasta 512 eventos<\/li>\n<li>Requiere: 01 &#8211; Bater\u00eda de respaldo (no incluido): 12V &#8211; 7 Ah\/4Ah.<br \/>\nINCLUYE: &#8211; 01 &#8211; PANEL VISTA128FBPT + (Incuye Transformador 220 VAC-3A).<\/li>\n<li>01 &#8211; TECLADO VI-6160CR.<\/li>\n<\/ul>\n","protected":false},"featured_media":19553,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1899],"product_tag":[1124,397,1121],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/19471"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=19471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/19553"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=19471"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=19471"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=19471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}