{"id":22918,"date":"2023-05-20T10:18:59","date_gmt":"2023-05-20T15:18:59","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=22918"},"modified":"2025-03-27T16:09:26","modified_gmt":"2025-03-27T21:09:26","slug":"bullet-4k-2-8mm-8mp-ipc-hfw3841e-as","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/bullet-4k-2-8mm-8mp-ipc-hfw3841e-as\/","title":{"rendered":"IPC-HFW3841E-AS | C\u00c1MARA BULLET 4K \/ 2.8mm \/ 8MP"},"content":{"rendered":"<div class=\"body-content show1\" data-v-2dd76d09=\"\">\n<div data-v-591ea1ea=\"\" data-v-2dd76d09=\"\">\n<div data-v-6538036b=\"\" data-v-591ea1ea=\"\">\n<div data-v-7e57a687=\"\" data-v-6538036b=\"\">\n<div class=\"product-detail-wrapper\" data-v-7e57a687=\"\">\n<div class=\"detail-text-wrapper\" data-v-7695a268=\"\" data-v-7e57a687=\"\">\n<div class=\"detail-tab-content container\" data-v-7695a268=\"\">\n<div class=\"tab-wraper\" data-v-7695a268=\"\">\n<div class=\"list-wrap\" data-v-7695a268=\"\">\n<div class=\"tab-left\" data-v-7695a268=\"\">\n<div class=\"selector-wrapper\" data-v-4faa2328=\"\" data-v-7695a268=\"\">\n<div class=\"selector-item\" data-v-4faa2328=\"\">\n<div class=\"selector-info\" data-v-4faa2328=\"\">\n<div data-v-393df75a=\"\">\n<p data-gtm-vis-has-fired-10552706_181=\"1\" data-gtm-vis-first-on-screen-10552706_184=\"1329\" data-gtm-vis-first-on-screen-10552706_192=\"1352\" data-gtm-vis-first-on-screen-10552706_193=\"1384\" data-gtm-vis-first-on-screen-10552706_194=\"1398\" data-gtm-vis-has-fired-10552706_195=\"1\" data-gtm-vis-first-on-screen-10552706_196=\"1425\" data-gtm-vis-first-on-screen-10552706_217=\"1446\" data-gtm-vis-recent-on-screen-10552706_192=\"8518\" data-gtm-vis-total-visible-time-10552706_192=\"100\" data-gtm-vis-has-fired-10552706_192=\"1\" data-gtm-vis-recent-on-screen-10552706_184=\"8519\" data-gtm-vis-total-visible-time-10552706_184=\"100\" data-gtm-vis-has-fired-10552706_184=\"1\" data-gtm-vis-recent-on-screen-10552706_196=\"8521\" data-gtm-vis-total-visible-time-10552706_196=\"100\" data-gtm-vis-has-fired-10552706_196=\"1\" data-gtm-vis-recent-on-screen-10552706_217=\"8522\" data-gtm-vis-total-visible-time-10552706_217=\"100\" data-gtm-vis-has-fired-10552706_217=\"1\" data-gtm-vis-recent-on-screen-10552706_194=\"8532\" data-gtm-vis-total-visible-time-10552706_194=\"100\" data-gtm-vis-has-fired-10552706_194=\"1\" data-gtm-vis-recent-on-screen-10552706_193=\"8616\" data-gtm-vis-total-visible-time-10552706_193=\"100\" data-gtm-vis-has-fired-10552706_193=\"1\">\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"tab-right\" data-v-7695a268=\"\">\n<div class=\"table-content\" data-v-7695a268=\"\">\n<div id=\"div_left\">\n<div class=\"div-drop\">\n<table id=\"table001\" class=\"NEW-TABLE TableOverride-1 tab-drag\">\n<tbody>\n<tr>\n<td colspan=\"60\">C\u00e1mara<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Sensor de imagen<\/td>\n<td colspan=\"42\">CMOS progresivo de 1\/2,8\u201d y 8 megap\u00edxeles<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">m\u00e1x.\u00a0Resoluci\u00f3n<\/td>\n<td colspan=\"42\">3840 (H) \u00d7 2160 (V)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">ROM<\/td>\n<td colspan=\"42\">128 MB<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">RAM<\/td>\n<td colspan=\"42\">512 megabytes<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Sistema de escaneo<\/td>\n<td colspan=\"42\">Progresivo<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Velocidad de obturaci\u00f3n electr\u00f3nica<\/td>\n<td colspan=\"42\">Autom\u00e1tico\/Manual 1\/3 s\u20131\/100 000 s<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">m\u00edn.\u00a0Iluminaci\u00f3n<\/td>\n<td colspan=\"42\">0,007 lux@F1.4 (color, 30IRE)<\/p>\n<p>0,0007 lux@F1.4 (B\/N, 30IRE)<\/p>\n<p>0 Lux (Iluminador encendido)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Relaci\u00f3n se\u00f1al\/ruido<\/td>\n<td colspan=\"42\">&gt; 56dB<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Distancia de iluminaci\u00f3n<\/td>\n<td colspan=\"42\">30 m (98,4 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Control de encendido\/apagado del iluminador<\/td>\n<td colspan=\"42\">Manual de auto<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">N\u00famero de iluminador<\/td>\n<td colspan=\"42\">1 (LED IR)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Rango de giro\/inclinaci\u00f3n\/rotaci\u00f3n<\/td>\n<td colspan=\"42\">Panor\u00e1mica: 0\u00b0\u2013360\u00b0<br \/>\nInclinaci\u00f3n: 0\u00b0\u201390\u00b0<br \/>\nRotaci\u00f3n: 0\u00b0\u2013360\u00b0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Lente<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tipo de lente<\/td>\n<td colspan=\"42\">Focal fijo<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tipo de montaje<\/td>\n<td colspan=\"42\">M12<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Longitud focal<\/td>\n<td colspan=\"42\">2,8 mm;\u00a03,6mm<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">m\u00e1x.\u00a0Abertura<\/td>\n<td colspan=\"42\">F1.4<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Campo de visi\u00f3n<\/td>\n<td colspan=\"42\">2,8 mm: Horizontal 108\u00b0 \u00d7 Vertical 58\u00b0 \u00d7 Diagonal 127\u00b0<br \/>\n3,6 mm: Horizontal 85\u00b0 \u00d7 Vertical 45\u00b0 \u00d7 Diagonal 100\u00b0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tipo de iris<\/td>\n<td colspan=\"42\">Fijado<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Distancia de enfoque cercano<\/td>\n<td colspan=\"42\">2,8 mm: 1,4 m (4,6 pies)<br \/>\n3,6 mm: 2,4 m (7,9 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\" rowspan=\"3\">Distancia DORI<\/td>\n<td colspan=\"8\">Lente<\/td>\n<td colspan=\"8\">Detectar<\/td>\n<td colspan=\"8\">Observar<\/td>\n<td colspan=\"8\">Reconocer<\/td>\n<td colspan=\"10\">Identificar<\/td>\n<\/tr>\n<tr>\n<td colspan=\"8\">2,8mm<\/td>\n<td colspan=\"8\">85,5 m (280,5 pies)<\/td>\n<td colspan=\"8\">34,2 metros<\/p>\n<p>(112,2 pies)<\/td>\n<td colspan=\"8\">17,1 metros<\/p>\n<p>(56,1 pies)<\/td>\n<td colspan=\"10\">8,6 metros<\/p>\n<p>(28,2 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"8\">3,6mm<\/td>\n<td colspan=\"8\">110,3 m (361,9 pies)<\/td>\n<td colspan=\"8\">44,1 metros<\/p>\n<p>(144,7 pies)<\/td>\n<td colspan=\"8\">22,1 metros<\/p>\n<p>(72,5 pies)<\/td>\n<td colspan=\"10\">11,0 metros<\/p>\n<p>(36,1 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">profesional, inteligente<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Protecci\u00f3n perimetral<\/td>\n<td colspan=\"42\">cable trampa;\u00a0intrusi\u00f3n (ayuda a la clasificaci\u00f3n y detecci\u00f3n precisa de veh\u00edculos y humanos)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">B\u00fasqueda inteligente<\/td>\n<td colspan=\"42\">Trabaje junto con Smart NVR para realizar b\u00fasquedas inteligentes refinadas, extracci\u00f3n de eventos y fusi\u00f3n con videos de eventos.<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Video<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Compresi\u00f3n de video<\/td>\n<td colspan=\"42\">H.265;\u00a0H.264;\u00a0H.264H;\u00a0H.264B;\u00a0MJPEG (solo compatible con la transmisi\u00f3n secundaria)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">C\u00f3dec inteligente<\/td>\n<td colspan=\"42\">Inteligente H.265+\/ Inteligente H.264+<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Velocidad de fotogramas de v\u00eddeo<\/td>\n<td colspan=\"42\">Convencional:<\/p>\n<p>3840 \u00d7 2160 @(1\u201320 fps por defecto)<\/p>\n<p>3840 \u00d7 2160 @(1\u201325\/30 fps cuando la funci\u00f3n AI est\u00e1 deshabilitada)<\/p>\n<p>Sub corriente:<\/p>\n<p>704 \u00d7 576 @ (1\u201325 fps)\/704 \u00d7 480 @ (1\u201330 fps)<\/p>\n<p>tercera corriente:<\/p>\n<p>1920 \u00d7 1080 @(1\u201325\/30 fps)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Capacidad de transmisi\u00f3n<\/td>\n<td colspan=\"42\">3 corrientes<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Resoluci\u00f3n<\/td>\n<td colspan=\"42\">8M (3840&#215;2160);\u00a06M (3072&#215;2048);\u00a05M (3072 x 1728\/2592 x 1944);\u00a04 millones (2688 x 1520);\u00a03M (2048&#215;1536\/2304&#215;1296);\u00a01080p (1920&#215;1080);\u00a01,3M (1280&#215;960);\u00a0720p (1280&#215;720);\u00a0P1 (704 x 576\/704 x 480);\u00a0VGA (640&#215;480);\u00a0CIF (352\u00d7288\/352\u00d7240)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Control de tasa de bits<\/td>\n<td colspan=\"42\">CBR\/VBR<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Bitrate de v\u00eddeo<\/td>\n<td colspan=\"42\">H.264: 3 kbps\u20138192 kbps<\/p>\n<p>H.265: 3 kbps\u20138192 kbps<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">D\u00eda\/Noche<\/td>\n<td colspan=\"42\">Autom\u00e1tico (ICR)\/Color\/B\/N<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">CLB<\/td>\n<td colspan=\"42\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">LLC<\/td>\n<td colspan=\"42\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">WDR<\/td>\n<td colspan=\"42\">120dB<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Autoadaptaci\u00f3n de la escena (SSA)<\/td>\n<td colspan=\"42\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Balance de blancos<\/td>\n<td colspan=\"42\">Autom\u00e1tico\/natural\/farola\/exterior\/manual\/aduana regional<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Ganar control<\/td>\n<td colspan=\"42\">Manual de auto<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Reducci\u00f3n de ruido<\/td>\n<td colspan=\"42\">DNR 3D<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Detecci\u00f3n de movimiento<\/td>\n<td colspan=\"42\">APAGADO\/ENCENDIDO (4 \u00e1reas, rectangular)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Regi\u00f3n de inter\u00e9s (RoI)<\/td>\n<td colspan=\"42\">S\u00ed (4 \u00e1reas)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Iluminaci\u00f3n inteligente<\/td>\n<td colspan=\"42\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Rotacion de imagen<\/td>\n<td colspan=\"42\">0\u00b0\/90\u00b0\/180\u00b0\/270\u00b0 (Admite 90\u00b0\/270\u00b0 con resoluci\u00f3n de 1080p e inferior).<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Espejo<\/td>\n<td colspan=\"42\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Enmascaramiento de privacidad<\/td>\n<td colspan=\"42\">4 \u00e1reas<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Audio<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">MICR\u00d3FONO incorporado<\/td>\n<td colspan=\"42\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Compresi\u00f3n de audio<\/td>\n<td colspan=\"42\">G.711a;\u00a0G.711Mu;\u00a0G726<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Alarma<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Evento de alarma<\/td>\n<td colspan=\"42\">&#8211; COMO:<br \/>\nSin tarjeta SD;\u00a0tarjeta SD llena;\u00a0error de la tarjeta SD;\u00a0advertencia de vida \u00fatil (solo compatible con la tarjeta Dahua);\u00a0desconexi\u00f3n de la red;\u00a0conflicto de IP;\u00a0acceso ilegal;\u00a0detecci\u00f3n de movimiento;\u00a0manipulaci\u00f3n de videos;\u00a0intrusi\u00f3n;\u00a0cable trampa;\u00a0cambio de escena;\u00a0detecci\u00f3n de audio;\u00a0detecci\u00f3n de voltaje;\u00a0alarma externa;\u00a0SMD;\u00a0excepci\u00f3n de seguridad<br \/>\n-SA:<br \/>\nSin tarjeta SD;\u00a0tarjeta SD llena;\u00a0error de la tarjeta SD;\u00a0advertencia de vida \u00fatil (solo compatible con la tarjeta Dahua);\u00a0desconexi\u00f3n de la red;\u00a0conflicto de IP;\u00a0acceso ilegal;\u00a0detecci\u00f3n de movimiento;\u00a0manipulaci\u00f3n de videos;\u00a0intrusi\u00f3n;\u00a0cable trampa;\u00a0cambio de escena;\u00a0detecci\u00f3n de audio;\u00a0detecci\u00f3n de voltaje;\u00a0SMD;\u00a0excepci\u00f3n de seguridad<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Red<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Red<\/td>\n<td colspan=\"42\">RJ-45 (10\/100 Base-T)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">SDK y API<\/td>\n<td colspan=\"42\">S\u00ed<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Protocolo<\/td>\n<td colspan=\"42\">IPv4;\u00a0IPv6;\u00a0HTTP;\u00a0TCP;\u00a0UDP;\u00a0PAR;\u00a0RTP;\u00a0RTSP;\u00a0RTCP;\u00a0RTMP;\u00a0SMTP;\u00a0FTP;\u00a0SFTP;\u00a0DHCP;\u00a0DNS;\u00a0DDNS;\u00a0calidad del servicio;\u00a0UPnP;\u00a0PNT;\u00a0multidifusi\u00f3n;\u00a0ICMP;\u00a0IGMP;\u00a0SNF;\u00a0SAMBA;\u00a0PPPoE;\u00a0SNMP<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">La seguridad cibern\u00e9tica<\/td>\n<td colspan=\"42\">cifrado de v\u00eddeo;\u00a0cifrado de firmware;\u00a0cifrado de configuraci\u00f3n;\u00a0Digerir;\u00a0WSSE;\u00a0bloqueo de cuenta;\u00a0registros de seguridad;\u00a0filtrado IP\/MAC;\u00a0generaci\u00f3n e importaci\u00f3n de la certificaci\u00f3n X.509;\u00a0registro del sistema;\u00a0HTTPS;\u00a0802.1x;\u00a0arranque de confianza;\u00a0ejecuci\u00f3n confiable;\u00a0actualizaci\u00f3n de confianza<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">interoperabilidad<\/td>\n<td colspan=\"42\">ONVIF (Perfil S\/Perfil G\/Perfil T);\u00a0CGI;\u00a0P2P;\u00a0Hito;\u00a0Genetec<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Usuario\/Anfitri\u00f3n<\/td>\n<td colspan=\"42\">20 (Ancho de banda total: 72 M)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Almacenamiento<\/td>\n<td colspan=\"42\">FTP;\u00a0SFTP;\u00a0Tarjeta Micro SD (admite m\u00e1x. 256 G);\u00a0NAS<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Navegador<\/td>\n<td colspan=\"42\">IE: IE8;\u00a0IE9;\u00a0IE11<br \/>\ncromo<br \/>\nFirefox<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">software de gesti\u00f3n<\/td>\n<td colspan=\"42\">PSS inteligente;\u00a0DSS;\u00a0DMSS<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tel\u00e9fono m\u00f3vil<\/td>\n<td colspan=\"42\">IOS;\u00a0Androide<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Certificaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Certificaciones<\/td>\n<td colspan=\"42\">CE-LVD: EN62368-1<br \/>\nCE-EMC: Directiva de compatibilidad electromagn\u00e9tica 2014\/30\/EU<br \/>\nFCC: 47 CFR FCC Parte 15, Subparte B<br \/>\nUL\/CUL: UL60950-1 CAN\/CSA C22.2 No.60950-1-07<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Puerto<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Entrada de audio<\/td>\n<td colspan=\"42\">1 canal (puerto RCA) (solo compatible con AS)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Salida de audio<\/td>\n<td colspan=\"42\">1 canal (puerto RCA) (solo compatible con AS)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Entrada de alarma<\/td>\n<td colspan=\"42\">1 canal de entrada: 5mA 3V\u20135V DC (Solo &#8211; compatible con AS)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Salida de alarma<\/td>\n<td colspan=\"42\">1 canal de salida: 300mA 12V DC (Solo &#8211; compatible con AS)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Fuerza<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Fuente de alimentaci\u00f3n<\/td>\n<td colspan=\"42\">12 V CC\/PoE (802.3af)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">El consumo de energ\u00eda<\/td>\n<td colspan=\"42\">Consumo b\u00e1sico de energ\u00eda: 3 W (12 V CC);\u00a03,5 W (PoE)<\/p>\n<p>m\u00e1x.\u00a0consumo de energ\u00eda (WDR + H.265 + intensidad LED IR): 5,5 W (12 V CC);\u00a06,3 W (PoE)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Ambiente<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Condiciones de operaci\u00f3n<\/td>\n<td colspan=\"42\">\u201340 \u00b0C a +60 \u00b0C (\u201340 \u00b0F a +140 \u00b0F)\/Menos del 95 % de HR<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Condiciones de almacenaje<\/td>\n<td colspan=\"42\">\u201340 \u00b0C a +60 \u00b0C (\u201340 \u00b0F a +140 \u00b0F)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Grado de protecci\u00f3n<\/td>\n<td colspan=\"42\">IP67<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Estructura<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Caja<\/td>\n<td colspan=\"42\">Metal<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Dimensiones<\/td>\n<td colspan=\"42\">192,7 mm \u00d7 70,5 mm \u00d7 66,4 mm (7,6&#8243; \u00d7 2,8&#8243; \u00d7 2,6&#8243;) (Largo \u00d7 Ancho \u00d7 Alto)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Peso neto<\/td>\n<td colspan=\"42\">590 g (1,3 libras)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Peso bruto<\/td>\n<td colspan=\"42\">780 g (1,7 libras)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<footer class=\"footer-wrap\" data-v-2dd76d09=\"\">\n<div class=\"container\">\n<div class=\"el-row\">\n<div class=\"el-col el-col-24 el-col-xs-24 el-col-sm-6 el-col-md-6 el-col-lg-6\">\n<div class=\"footer-newsletter\"><\/div>\n<\/div>\n<div class=\"hidden-xs el-col el-col-24 el-col-xs-18 el-col-sm-18 el-col-md-18 el-col-lg-18\"><\/div>\n<\/div>\n<\/div>\n<\/footer>\n","protected":false},"excerpt":{"rendered":"<div style=\"text-align: justify\">La <strong>IPC-HFW3841E-AS<\/strong> es una c\u00e1mara <strong>bullet<\/strong> de <strong>8 megap\u00edxeles<\/strong> dise\u00f1ada para ofrecer im\u00e1genes de alta resoluci\u00f3n. Con tecnolog\u00eda de <strong>visi\u00f3n infrarroja (IR)<\/strong>, proporciona monitoreo efectivo en condiciones de poca luz o total oscuridad. Su dise\u00f1o robusto la hace ideal para su uso en exteriores, resistiendo condiciones clim\u00e1ticas adversas. Adem\u00e1s, es compatible con la compresi\u00f3n <strong>H.265<\/strong>, lo que optimiza el almacenamiento y la transmisi\u00f3n de video, y es perfecta para aplicaciones de seguridad avanzadas en entornos residenciales o comerciales.<\/div>\n","protected":false},"featured_media":22921,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[1783,1775],"product_tag":[2486,191,226,51],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/22918"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=22918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/22921"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=22918"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=22918"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=22918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}