{"id":24087,"date":"2024-08-09T17:35:16","date_gmt":"2024-08-09T22:35:16","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=24087"},"modified":"2024-08-09T17:35:18","modified_gmt":"2024-08-09T22:35:18","slug":"ipc-s2xn-6m0wed-camara-ranger-dual-lens-6-mp","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/ipc-s2xn-6m0wed-camara-ranger-dual-lens-6-mp\/","title":{"rendered":"IPC-S2XN-6M0WED | CAMARA RANGER DUAL LENS &#8211; 6 MP"},"content":{"rendered":"<p id=\"tw-target-text\" class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Traducci\u00f3n\" aria-label=\"Texto traducido\" data-ved=\"2ahUKEwjRismY6-iHAxV6P7kGHQTmBVoQ3ewLegQIEhAU\"><span class=\"Y2IQFc\" lang=\"es\">La lente fija de 3MP\/2K y la lente PT de 3MP\/2K proporcionan dos im\u00e1genes en una sola c\u00e1mara. Con el monitoreo en vivo de doble lente y la funci\u00f3n panor\u00e1mica de giro e inclinaci\u00f3n, el Ranger Dual garantiza que cada rinc\u00f3n de su hogar est\u00e9 completamente cubierto. Es compatible Cuatro modos de visi\u00f3n nocturna para una claridad diurna incluso en plena oscuridad. La detecci\u00f3n de humanos\/mascotas encuentra r\u00e1pidamente eventos en im\u00e1genes y le env\u00eda inmediatamente una notificaci\u00f3n. Con foco y sirena incorporados, el Ranger Dual mantiene activamente visitantes no deseados lejos de lo que le importa. El modo de privacidad ayuda a proteger su privacidad personal cuando est\u00e1n en casa y la funci\u00f3n Smart Tracking permite que la c\u00e1mara siga objetos en movimiento cuando detecta movimiento.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>IPC-S2XN-6M0WED &#8211; NUEVO &#8211; CAMARA RANGER DUAL LENS &#8211; 6 MP &#8211; 3MP LENTE FIJO + 3MP LENTE PAN &amp; TILT &#8211; PN INTERNAL IPC-S2XN-6M0WED-IMOU<\/p>\n<p class=\"tw-data-text tw-text-large tw-ta\" dir=\"ltr\" data-placeholder=\"Traducci\u00f3n\" aria-label=\"Texto traducido\" data-ved=\"2ahUKEwjBhovgooOGAxXmq5UCHT_iBFgQ3ewLegQIBRAU\"><a href=\"https:\/\/waytec.pe\/productos\/wp-content\/uploads\/2024\/08\/IPCS2XN6M0WED-download-1-1719241265952.pdf\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-19065\" src=\"https:\/\/waytec.pe\/productos\/wp-content\/uploads\/2021\/11\/descarga.png\" alt=\"\" width=\"80\" height=\"80\" srcset=\"https:\/\/waytec.pe\/productos\/wp-content\/uploads\/2021\/11\/descarga.png 225w, https:\/\/waytec.pe\/productos\/wp-content\/uploads\/2021\/11\/descarga-200x200.png 200w, https:\/\/waytec.pe\/productos\/wp-content\/uploads\/2021\/11\/descarga-100x100.png 100w, https:\/\/waytec.pe\/productos\/wp-content\/uploads\/2021\/11\/descarga-64x64.png 64w\" sizes=\"(max-width: 80px) 100vw, 80px\" \/><\/a><\/p>\n<div><a href=\"https:\/\/waytec.pe\/productos\/wp-content\/uploads\/2024\/08\/IPCS2XN6M0WED-download-1-1719241265952.pdf\" target=\"_blank\" rel=\"noopener\"><strong>VER DATASHEET<\/strong><\/a><\/div>\n","protected":false},"featured_media":24090,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[1781],"product_tag":[123,2443,1494],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/24087"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=24087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/24090"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=24087"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=24087"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=24087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}