{"id":4551,"date":"2020-01-10T17:30:22","date_gmt":"2020-01-10T22:30:22","guid":{"rendered":"https:\/\/waytec.pe\/productos\/?post_type=product&#038;p=4551"},"modified":"2024-04-21T21:26:19","modified_gmt":"2024-04-22T02:26:19","slug":"lite-bullet2k-2-7-12mm-4mp-cbvs-hdcvi-hac-hfw1400r-z-ire6-poc-s2","status":"publish","type":"product","link":"https:\/\/waytec.pe\/productos\/p\/lite-bullet2k-2-7-12mm-4mp-cbvs-hdcvi-hac-hfw1400r-z-ire6-poc-s2\/","title":{"rendered":"LITE &#8211; BULLET2K\/ 2.7-12mm \/ 4MP CBVS \/ HDCVI &#8211; HAC-HFW1400R-Z-IRE6-POC-S2"},"content":{"rendered":"<div id=\"div_left\">\n<div class=\"div-drop\">\n<table id=\"table001\" class=\"NEW-TABLE TableOverride-1 tab-drag\">\n<tbody>\n<tr>\n<td colspan=\"60\">C\u00e1mara<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Sensor de imagen<\/td>\n<td colspan=\"42\">CMOS de 1\/2,7&#8243;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">P\u00edxeles efectivos<\/td>\n<td colspan=\"42\">2560 (H) \u00d7 1440 (V), 4MP<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Sistema de escaneo<\/td>\n<td colspan=\"42\">Progresivo<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Velocidad de obturaci\u00f3n electr\u00f3nica<\/td>\n<td colspan=\"42\">PAL: 1\/25~1\/100000 s<\/p>\n<p>NTSC: 1\/30~1\/100000 s<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">iluminaci\u00f3n m\u00ednima<\/td>\n<td colspan=\"42\">0.03Lux\/F1.8, 30IRE, 0Lux\/F1.8 (IR encendido)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Relaci\u00f3n se\u00f1al\/ruido<\/td>\n<td colspan=\"42\">M\u00e1s de\u00a065dB<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Distancia de infrarrojos<\/td>\n<td colspan=\"42\">Hasta 60 m (197 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Control de encendido\/apagado de infrarrojos<\/td>\n<td colspan=\"42\">Manual de auto<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">LED IR<\/td>\n<td colspan=\"42\">4<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Lente<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tipo de lente<\/td>\n<td colspan=\"42\">Lente motorizada \/ Iris fijo<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Tipo de montaje<\/td>\n<td colspan=\"42\">Junta de entrada<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Longitud focal<\/td>\n<td colspan=\"42\">2,7-12 mm<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Apertura m\u00e1xima<\/td>\n<td colspan=\"42\">F1.8<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Punto de vista<\/td>\n<td colspan=\"42\">Alto: 92\u00b0~29\u00b0<\/p>\n<p>V: 49\u00b0~16\u00b0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Control de enfoque<\/td>\n<td colspan=\"42\">Motorizado<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Distancia de enfoque cercano<\/td>\n<td colspan=\"42\">800 mm<\/p>\n<p>31,50&#8221;<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Panor\u00e1mica \/ Inclinaci\u00f3n \/ Rotaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Panor\u00e1mica\/Inclinaci\u00f3n\/Rotaci\u00f3n<\/td>\n<td colspan=\"42\">Panor\u00e1mica: 0\u00b0 ~ 360\u00b0<\/p>\n<p>Inclinaci\u00f3n: 0\u00b0 ~ 87\u00b0<\/p>\n<p>Rotaci\u00f3n: 0\u00b0 ~ 360\u00b0<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Video<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Resoluci\u00f3n<\/td>\n<td colspan=\"42\">4 MP (2560 \u00d7 1440)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Velocidad\u00a0de fotogramas<\/td>\n<td colspan=\"42\">25\/30fps@4MP, 25\/30fps@1080P<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Salida de v\u00eddeo<\/td>\n<td colspan=\"42\">Salida de video de alta definici\u00f3n BNC de 1 canal\/salida de video CVBS (puede cambiar)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">D\u00eda\/Noche<\/td>\n<td colspan=\"42\">Autom\u00e1tico (ICR) \/ Manual<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Men\u00fa OSD<\/td>\n<td colspan=\"42\">Multi lenguaje<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Modo BLC<\/td>\n<td colspan=\"42\">BLC\/HLC\/DWDR<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">WDR<\/td>\n<td colspan=\"42\">DWDR<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Ganar control<\/td>\n<td colspan=\"42\">CAG<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Reducci\u00f3n de ruido<\/td>\n<td colspan=\"42\">2D<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Balance de blancos<\/td>\n<td colspan=\"42\">Manual de auto<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">IR inteligente<\/td>\n<td colspan=\"42\">Manual de auto<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div id=\"div_left\">\n<div class=\"div-drop\">\n<table id=\"table002\" class=\"NEW-TABLE TableOverride-1 tab-drag\">\n<tbody>\n<tr>\n<td colspan=\"60\">Distancia DORI<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Nota: La distancia DORI es una &#8220;proximidad general&#8221; de la distancia que facilita la identificaci\u00f3n de la c\u00e1mara adecuada para sus necesidades.\u00a0La distancia DORI se calcula seg\u00fan la especificaci\u00f3n del sensor y el resultado de la prueba de laboratorio seg\u00fan EN 62676-4, que define los criterios para Detectar, Observar, Reconocer e Identificar respectivamente.<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\" rowspan=\"2\"><\/td>\n<td colspan=\"21\" rowspan=\"2\">DORI<\/p>\n<p>Definici\u00f3n<\/td>\n<td colspan=\"21\">Distancia<\/td>\n<\/tr>\n<tr>\n<td colspan=\"10\">Ancho<\/td>\n<td colspan=\"11\">tele<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Detectar<\/td>\n<td colspan=\"14\">25 px\/m (8 px\/pie)<\/td>\n<td colspan=\"14\">67 m (220 pies)<\/td>\n<td colspan=\"14\">198 m (650 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Observar<\/td>\n<td colspan=\"14\">63 px\/m (19 px\/pie)<\/td>\n<td colspan=\"14\">27 m (89 pies)<\/td>\n<td colspan=\"14\">79 m (259 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Reconocer<\/td>\n<td colspan=\"14\">125 px\/m (38 px\/pie)<\/td>\n<td colspan=\"14\">13 m (43 pies)<\/td>\n<td colspan=\"14\">39 m (128 pies)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Identificar<\/td>\n<td colspan=\"14\">250 px\/m (76 px\/pie)<\/td>\n<td colspan=\"14\">7 m (22 pies)<\/td>\n<td colspan=\"14\">19 m (62 pies)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<div id=\"div_left\">\n<div class=\"div-drop\">\n<table id=\"table003\" class=\"NEW-TABLE TableOverride-1 tab-drag\">\n<tbody>\n<tr>\n<td colspan=\"60\">Certificaciones<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Certificaciones<\/td>\n<td colspan=\"42\">CE (EN55032, EN55024, EN50130-4)<\/p>\n<p>FCC (CFR 47 FCC Parte 15 subparte B, ANSI C63.4-2014)<\/p>\n<p>UL (UL60950-1+CAN\/CSA C22.2 No.60950-1)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Interfaz<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Interfaz de audio<\/td>\n<td colspan=\"42\">N \/ A<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">electrico<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Fuente de alimentaci\u00f3n<\/td>\n<td colspan=\"42\">POC\u00a0<span lang=\"zh-CN\">\/\u00a0<\/span>12 V CC \u00b130 %<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">El consumo de energ\u00eda<\/td>\n<td colspan=\"42\">POC\u00a0<span lang=\"zh-CN\">\/\u00a0<\/span>m\u00e1x. 7,1 W (12 V CC, IR activado)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Ambiental<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Condiciones de\u00a0funcionamiento<\/td>\n<td colspan=\"42\">-30 \u00b0C ~ +60 \u00b0C (-22 \u00b0F ~ +140 \u00b0F) \/ Menos del 95 % de HR<\/p>\n<p>* La puesta en marcha debe realizarse por encima de -30 \u00b0C (-22 \u00b0F)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Condiciones de almacenaje<\/td>\n<td colspan=\"42\">-30 \u00b0C ~ +60 \u00b0C (-22 \u00b0F ~ +140 \u00b0F) \/ Menos del 95 % de HR<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Protecci\u00f3n de entrada y resistencia al vandalismo<\/td>\n<td colspan=\"42\">IP67<\/td>\n<\/tr>\n<tr>\n<td colspan=\"60\">Construcci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Caja<\/td>\n<td colspan=\"42\">Aluminio<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Dimensiones<\/td>\n<td colspan=\"42\">209,9 mm \u00d7 90,4 mm \u00d7 90,4 mm (8,26&#8243; \u00d7 3,56&#8243; \u00d7 3,56&#8243;)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Peso neto<\/td>\n<td colspan=\"42\">0,57 kg (1,26 libras)<\/td>\n<\/tr>\n<tr>\n<td colspan=\"18\">Peso bruto<\/td>\n<td colspan=\"42\">0,74 kg (1,63 libras)<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>LITE &#8211; BULLET2K\/ 2.7-12mm \/ 4MP CBVS \/ HDCVI<\/p>\n<p>+ 25\/30fps@4MP, 25\/30fps@1080P+ Max. IR length 60m, Smart IR+ IP67+ METAL<\/p>\n","protected":false},"featured_media":16512,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_cat":[462],"product_tag":[334,210,119,51],"_links":{"self":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product\/4551"}],"collection":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/comments?post=4551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media\/16512"}],"wp:attachment":[{"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/media?parent=4551"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_cat?post=4551"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/waytec.pe\/productos\/wp-json\/wp\/v2\/product_tag?post=4551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}